{"id":1630,"date":"2021-11-04T10:40:42","date_gmt":"2021-11-04T09:40:42","guid":{"rendered":"https:\/\/esz.dyncom.de\/?p=1630"},"modified":"2024-02-06T14:26:04","modified_gmt":"2024-02-06T13:26:04","slug":"esz-ag-und-siglent-technologies-kooperieren","status":"publish","type":"post","link":"https:\/\/esz.dyncom.de\/en\/esz-ag-und-siglent-technologies-kooperieren\/","title":{"rendered":"esz AG und Siglent Technologies kooperieren"},"content":{"rendered":"<p>Die esz AG calibration &amp; metrology und Siglent Technologies werden zuk\u00fcnftig im Bereich der akkreditierten Kalibrierungen innerhalb Europas zusammenarbeiten.<\/p>\n<p>Bereits seit l\u00e4ngerem nutzt Siglent Technologies den Kalibrierservice der esz AG f\u00fcr ihre Neuger\u00e4te. Nun wollen die beiden Unternehmen enger zusammenarbeiten. Die esz AG wird zuk\u00fcnftig europaweit die akkreditierten Kalibrierungen von Siglent Technologies Messger\u00e4ten \u00fcbernehmen. Die Kooperation umfasst die Kalibrierung von Neuger\u00e4ten vor der Auslieferung sowie die Justierung von Bestandger\u00e4ten im Bedarfsfall.<\/p>\n<p>Die ganze Pressemitteilung lesen Sie <a href=\"https:\/\/www.esz-ag.de\/downloads\/press\/3595\/open\/pressemitteilung-esz-ag-unterstuetzt-nachbarschaftshilfe-eichenau.pdf\" target=\"_blank\" rel=\"noopener\">hier<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die esz AG calibration &amp; metrology und Siglent Technologies werden zuk\u00fcnftig im Bereich der akkreditierten&#8230;<\/p>\n","protected":false},"author":22,"featured_media":47967,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1630","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert"],"acf":[],"_links":{"self":[{"href":"https:\/\/esz.dyncom.de\/en\/wp-json\/wp\/v2\/posts\/1630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esz.dyncom.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esz.dyncom.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esz.dyncom.de\/en\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/esz.dyncom.de\/en\/wp-json\/wp\/v2\/comments?post=1630"}],"version-history":[{"count":0,"href":"https:\/\/esz.dyncom.de\/en\/wp-json\/wp\/v2\/posts\/1630\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esz.dyncom.de\/en\/wp-json\/wp\/v2\/media\/47967"}],"wp:attachment":[{"href":"https:\/\/esz.dyncom.de\/en\/wp-json\/wp\/v2\/media?parent=1630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esz.dyncom.de\/en\/wp-json\/wp\/v2\/categories?post=1630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esz.dyncom.de\/en\/wp-json\/wp\/v2\/tags?post=1630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}